{"id":17604,"date":"2025-08-27T15:05:40","date_gmt":"2025-08-27T13:05:40","guid":{"rendered":"https:\/\/www.carseatsandparts.com\/?post_type=product&#038;p=17604"},"modified":"2025-12-18T08:23:57","modified_gmt":"2025-12-18T07:23:57","slug":"fiat-ducato-bekleding-panorama","status":"publish","type":"product","link":"https:\/\/www.carseatsandparts.com\/de\/product\/fiat-ducato-bekleding-panorama\/","title":{"rendered":"Fiat Ducato Polsterm\u00f6bel PANORAMA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"Der Fiat-Stoff ist f\u00fcr den Ducato 1994 - 1999 geeignet. Flaches Gewebe mit schachbrettartigen Bl\u00f6cken. Name des Herstellers: PANORAMA","protected":false},"featured_media":17605,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[1942],"product_cat":[2861,225],"product_tag":[2888],"class_list":{"0":"post-17604","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-fiat","7":"product_cat-bekleding-voor-bedrijfswagens","8":"product_cat-per-strekkende-meter","9":"product_tag-fiat18188","10":"product_shipping_class-onderdelen-console","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":null,"yoast_head_json":null,"_links":{"self":[{"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product\/17604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/comments?post=17604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/media\/17605"}],"wp:attachment":[{"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/media?parent=17604"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product_brand?post=17604"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product_cat?post=17604"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product_tag?post=17604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}