{"id":17809,"date":"2025-09-04T09:35:45","date_gmt":"2025-09-04T07:35:45","guid":{"rendered":"https:\/\/www.carseatsandparts.com\/?post_type=product&#038;p=17809"},"modified":"2025-12-05T10:58:06","modified_gmt":"2025-12-05T09:58:06","slug":"nissan-nv200-cabstar-bekleding-antraciet","status":"publish","type":"product","link":"https:\/\/www.carseatsandparts.com\/de\/product\/nissan-nv200-cabstar-bekleding-antraciet\/","title":{"rendered":"Nissan NV200 Cabstar Polsterung Anthrazit"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"De Nissan stof is geschikt voor de NV200 Cabstar van bouwjaar 2013 &#8211; heden. Gaasweefsel met gleufjes.","protected":false},"featured_media":17810,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[2000],"product_cat":[2861,225],"product_tag":[3054],"class_list":{"0":"post-17809","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-nissan","7":"product_cat-bekleding-voor-bedrijfswagens","8":"product_cat-per-strekkende-meter","9":"product_tag-niss12068","10":"product_shipping_class-onderdelen-console","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":null,"yoast_head_json":null,"_links":{"self":[{"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product\/17809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/comments?post=17809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/media\/17810"}],"wp:attachment":[{"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/media?parent=17809"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product_brand?post=17809"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product_cat?post=17809"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/de\/wp-json\/wp\/v2\/product_tag?post=17809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}