{"id":17819,"date":"2025-09-04T09:51:37","date_gmt":"2025-09-04T07:51:37","guid":{"rendered":"https:\/\/www.carseatsandparts.com\/?post_type=product&#038;p=17819"},"modified":"2025-12-05T10:55:15","modified_gmt":"2025-12-05T09:55:15","slug":"nissan-primastar-sri-bekleding-antraciet","status":"publish","type":"product","link":"https:\/\/www.carseatsandparts.com\/en\/product\/nissan-primastar-sri-bekleding-antraciet\/","title":{"rendered":"Nissan Primastar Sri Upholstery Anthracite"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"De Nissan stof is geschikt voor de Primastar Sri van bouwjaar 2003 &#8211; heden. Antraciet met diagonaal fantasie blok figuren in rood\/groen\/paars.","protected":false},"featured_media":17820,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[2000],"product_cat":[2861,225],"product_tag":[3064],"class_list":{"0":"post-17819","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-nissan","7":"product_cat-bekleding-voor-bedrijfswagens","8":"product_cat-per-strekkende-meter","9":"product_tag-niss17068","10":"product_shipping_class-onderdelen-console","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"exclude_global_add_ons":[],"addons":[],"acf":[],"yoast_head":null,"yoast_head_json":null,"_links":{"self":[{"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/product\/17819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/comments?post=17819"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/media\/17820"}],"wp:attachment":[{"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/media?parent=17819"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/product_brand?post=17819"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/product_cat?post=17819"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.carseatsandparts.com\/en\/wp-json\/wp\/v2\/product_tag?post=17819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}